{"id":5226,"date":"2022-02-12T00:29:33","date_gmt":"2022-02-11T23:29:33","guid":{"rendered":"https:\/\/geneve.wordcamp.org\/2022\/?post_type=wcb_session&#038;p=5226"},"modified":"2022-05-05T20:04:05","modified_gmt":"2022-05-05T18:04:05","slug":"est-ce-que-mon-site-est-de-qualite","status":"publish","type":"wcb_session","link":"https:\/\/geneve.wordcamp.org\/2022\/session\/est-ce-que-mon-site-est-de-qualite\/","title":{"rendered":"Est-ce que mon site est de qualit\u00e9 ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Faire un site web, \u00e7a para\u00eet souvent facile m\u00eame pour ceux qui ne savent pas comment faire. Un peu de texte, deux ou trois images, une vid\u00e9o\u2026 il n\u2019y a rien de compliqu\u00e9. Et c\u2019est vrai qu\u2019il existe de nombreux outils facilitant la vie des cr\u00e9ateurs de contenus en ligne de nos jours, parmi lesquels WordPress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais produire un site web de qualit\u00e9, c\u2019est une autre histoire !<br>Derri\u00e8re l\u2019apparente simplicit\u00e9 d\u2019un site ou d\u2019un service web, nous verrons qu\u2019il y a un tr\u00e8s large spectre de sujets et de th\u00e9matiques \u00e0 prendre en compte pour assurer \u00e0 nos utilisateurs une exp\u00e9rience r\u00e9ussie.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/U4X4D8P4Ppc?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent&#038;listType=playlist&#038;list=PLR8aRlBtuh6Oiw_TyJJBbuWSMMh6nulVk\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline\">Slides:<\/span> <a href=\"https:\/\/speakerdeck.com\/kloh\/est-ce-que-mon-site-est-de-qualite-wordcamp-geneve-2022\">https:\/\/speakerdeck.com\/kloh\/est-ce-que-mon-site-est-de-qualite-wordcamp-geneve-2022<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faire un site web, \u00e7a para\u00eet souvent facile m\u00eame pour ceux qui ne savent pas comment faire. Un peu de texte, deux ou trois images, une vid\u00e9o\u2026 il n\u2019y a rien de compliqu\u00e9. Et c\u2019est vrai qu\u2019il existe de nombreux outils facilitant la vie des cr\u00e9ateurs de contenus en ligne de nos jours, parmi lesquels [&hellip;]<\/p>\n","protected":false},"author":14468419,"featured_media":0,"template":"wp-custom-template-wcgva-image-non-sponsors-oui","meta":{"_crdt_document":"","_wcpt_session_time":1649515800,"_wcpt_session_duration":900,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[3375],"footnotes":""},"session_track":[45],"session_category":[42],"class_list":["post-5226","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-1-conference-talks","wcb_session_category-format-court-short-talk"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"9 avril 2022","time":"16:50"},"session_speakers":[{"id":"3375","slug":"luc-poupard","name":"Luc Poupard","link":"https:\/\/geneve.wordcamp.org\/2022\/speaker\/luc-poupard\/"}],"session_cats_rendered":"Format court \/ Short talk","_links":{"self":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":3,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5226\/revisions"}],"predecessor-version":[{"id":6789,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5226\/revisions\/6789"}],"speakers":[{"embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/speakers\/3375"}],"author":[{"embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wporg\/v1\/users\/kloh"}],"wp:attachment":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/media?parent=5226"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/session_track?post=5226"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/session_category?post=5226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}