{"id":5129,"date":"2022-02-07T11:22:47","date_gmt":"2022-02-07T10:22:47","guid":{"rendered":"https:\/\/geneve.wordcamp.org\/2022\/?post_type=wcb_session&#038;p=5129"},"modified":"2022-05-05T20:01:03","modified_gmt":"2022-05-05T18:01:03","slug":"le-seo-cest-super-choisir-ses-outils-et-ses-ressources-pour-repondre-a-sa-clientele","status":"publish","type":"wcb_session","link":"https:\/\/geneve.wordcamp.org\/2022\/session\/le-seo-cest-super-choisir-ses-outils-et-ses-ressources-pour-repondre-a-sa-clientele\/","title":{"rendered":"Le SEO c\u2019est super! Choisir ses outils et ses ressources pour r\u00e9pondre \u00e0 sa client\u00e8le"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En tant que d\u00e9veloppeuse ou d\u00e9veloppeur WP que devriez-vous savoir \u00e0 propos du SEO? Cette conf\u00e9rence d\u00e9marre avec un r\u00e9capitulatif du fonctionnement de Google (crawling &amp; indexation) puis Isaline partagera les types de projets WP sur lesquels elle est le plus intervenue durant les 2 derni\u00e8res ann\u00e9es.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durant cette conf\u00e9rence vous apprendrez:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le fonctionnement d\u2019un robot crawler,<\/li><li>les erreurs classiques \u00e0 \u00e9viter,<\/li><li>les plugins favoris d\u2019Isaline,<\/li><li>des outils d\u2019analyse gratuits et payants,<\/li><li>ce que vous pouvez attendre d\u2019une collaboration avec une sp\u00e9cialiste SEO.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">NB: Cette conf\u00e9rence est pr\u00e9vue pour vous donner envie de creuser le sujet du SEO avec des ressources pertinentes et vous cr\u00e9er votre propre \u2018fiche de triche\u2019 pour r\u00e9pondre \u00e0 votre client\u00e8le.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conf\u00e9rence ad\u00e9quate pour les d\u00e9butant\u00b7es en SEO. Isaline partagera des lectures pour que les avanc\u00e9\u00b7es puissent \u00e9tudier le sujet en toute ind\u00e9pendance.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/6SBcM7CfqQc?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent&#038;listType=playlist&#038;list=PLR8aRlBtuh6Oiw_TyJJBbuWSMMh6nulVk\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline\">Slides:<\/span> <a href=\"https:\/\/www.slideshare.net\/IsalineMlhauser\/le-seo-cest-super-wordcamp-genve-2022\">https:\/\/www.slideshare.net\/IsalineMlhauser\/le-seo-cest-super-wordcamp-genve-2022<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant que d\u00e9veloppeuse ou d\u00e9veloppeur WP que devriez-vous savoir \u00e0 propos du SEO? Cette conf\u00e9rence d\u00e9marre avec un r\u00e9capitulatif du fonctionnement de Google (crawling &amp; indexation) puis Isaline partagera les types de projets WP sur lesquels elle est le plus intervenue durant les 2 derni\u00e8res ann\u00e9es.&nbsp; Durant cette conf\u00e9rence vous apprendrez: le fonctionnement d\u2019un [&hellip;]<\/p>\n","protected":false},"author":17710553,"featured_media":0,"template":"wp-custom-template-wcgva-image-non-sponsors-oui","meta":{"_crdt_document":"","_wcpt_session_time":1649491200,"_wcpt_session_duration":2100,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[3353],"footnotes":""},"session_track":[45],"session_category":[41],"class_list":["post-5129","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-1-conference-talks","wcb_session_category-conference-long-talk"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"9 avril 2022","time":"10:00"},"session_speakers":[{"id":"3353","slug":"isaline-muelhauser","name":"Isaline Muelhauser","link":"https:\/\/geneve.wordcamp.org\/2022\/speaker\/isaline-muelhauser\/"}],"session_cats_rendered":"Conf\u00e9rence \/ Long talk","_links":{"self":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":5,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5129\/revisions"}],"predecessor-version":[{"id":6779,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/sessions\/5129\/revisions\/6779"}],"speakers":[{"embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/speakers\/3353"}],"author":[{"embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wporg\/v1\/users\/isaline"}],"wp:attachment":[{"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/media?parent=5129"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/session_track?post=5129"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/geneve.wordcamp.org\/2022\/wp-json\/wp\/v2\/session_category?post=5129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}